{"id":2341,"date":"2022-11-07T12:19:46","date_gmt":"2022-11-07T12:19:46","guid":{"rendered":"https:\/\/www.conventuspolymers.com\/compuestos-personalizados\/"},"modified":"2024-05-03T16:48:35","modified_gmt":"2024-05-03T16:48:35","slug":"compuestos-personalizados","status":"publish","type":"page","link":"https:\/\/www.conventuspolymers.com\/es\/productos\/compuestos-personalizados\/","title":{"rendered":"Compuestos personalizados"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":2578,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2341","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compuestos y masterbatches - Productos | Conventus Polymers<\/title>\n<meta name=\"description\" content=\"Conventus Polymers cuenta con una amplia cartera de resinas termopl\u00e1sticas, refuerzos y aditivos, y propiedades personalizables. M\u00e1s informaci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conventuspolymers.com\/es\/productos\/compuestos-personalizados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compuestos y masterbatches - Productos | Conventus Polymers\" \/>\n<meta property=\"og:description\" content=\"Conventus Polymers cuenta con una amplia cartera de resinas termopl\u00e1sticas, refuerzos y aditivos, y propiedades personalizables. M\u00e1s informaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conventuspolymers.com\/es\/productos\/compuestos-personalizados\/\" \/>\n<meta property=\"og:site_name\" content=\"Conventus Polymers\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-03T16:48:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/productos\\\/compuestos-personalizados\\\/\",\"url\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/productos\\\/compuestos-personalizados\\\/\",\"name\":\"Compuestos y masterbatches - Productos | Conventus Polymers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/#website\"},\"datePublished\":\"2022-11-07T12:19:46+00:00\",\"dateModified\":\"2024-05-03T16:48:35+00:00\",\"description\":\"Conventus Polymers cuenta con una amplia cartera de resinas termopl\u00e1sticas, refuerzos y aditivos, y propiedades personalizables. M\u00e1s informaci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/productos\\\/compuestos-personalizados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/productos\\\/compuestos-personalizados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/productos\\\/compuestos-personalizados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Compuestos personalizados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/\",\"name\":\"Conventus Polymers\",\"description\":\"High-Performance Polymers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/#organization\",\"name\":\"Conventus Polymers\",\"url\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.conventuspolymers.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LogoFinal.jpg\",\"contentUrl\":\"https:\\\/\\\/www.conventuspolymers.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LogoFinal.jpg\",\"width\":800,\"height\":183,\"caption\":\"Conventus Polymers\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conventuspolymers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/conventus-polymers\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compuestos y masterbatches - Productos | Conventus Polymers","description":"Conventus Polymers cuenta con una amplia cartera de resinas termopl\u00e1sticas, refuerzos y aditivos, y propiedades personalizables. M\u00e1s informaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conventuspolymers.com\/es\/productos\/compuestos-personalizados\/","og_locale":"es_ES","og_type":"article","og_title":"Compuestos y masterbatches - Productos | Conventus Polymers","og_description":"Conventus Polymers cuenta con una amplia cartera de resinas termopl\u00e1sticas, refuerzos y aditivos, y propiedades personalizables. M\u00e1s informaci\u00f3n","og_url":"https:\/\/www.conventuspolymers.com\/es\/productos\/compuestos-personalizados\/","og_site_name":"Conventus Polymers","article_modified_time":"2024-05-03T16:48:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.conventuspolymers.com\/es\/productos\/compuestos-personalizados\/","url":"https:\/\/www.conventuspolymers.com\/es\/productos\/compuestos-personalizados\/","name":"Compuestos y masterbatches - Productos | Conventus Polymers","isPartOf":{"@id":"https:\/\/www.conventuspolymers.com\/es\/#website"},"datePublished":"2022-11-07T12:19:46+00:00","dateModified":"2024-05-03T16:48:35+00:00","description":"Conventus Polymers cuenta con una amplia cartera de resinas termopl\u00e1sticas, refuerzos y aditivos, y propiedades personalizables. M\u00e1s informaci\u00f3n","breadcrumb":{"@id":"https:\/\/www.conventuspolymers.com\/es\/productos\/compuestos-personalizados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conventuspolymers.com\/es\/productos\/compuestos-personalizados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.conventuspolymers.com\/es\/productos\/compuestos-personalizados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.conventuspolymers.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/www.conventuspolymers.com\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Compuestos personalizados"}]},{"@type":"WebSite","@id":"https:\/\/www.conventuspolymers.com\/es\/#website","url":"https:\/\/www.conventuspolymers.com\/es\/","name":"Conventus Polymers","description":"High-Performance Polymers","publisher":{"@id":"https:\/\/www.conventuspolymers.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conventuspolymers.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.conventuspolymers.com\/es\/#organization","name":"Conventus Polymers","url":"https:\/\/www.conventuspolymers.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conventuspolymers.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.conventuspolymers.com\/wp-content\/uploads\/2022\/12\/LogoFinal.jpg","contentUrl":"https:\/\/www.conventuspolymers.com\/wp-content\/uploads\/2022\/12\/LogoFinal.jpg","width":800,"height":183,"caption":"Conventus Polymers"},"image":{"@id":"https:\/\/www.conventuspolymers.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/conventus-polymers\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.conventuspolymers.com\/es\/wp-json\/wp\/v2\/pages\/2341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conventuspolymers.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.conventuspolymers.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.conventuspolymers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conventuspolymers.com\/es\/wp-json\/wp\/v2\/comments?post=2341"}],"version-history":[{"count":3,"href":"https:\/\/www.conventuspolymers.com\/es\/wp-json\/wp\/v2\/pages\/2341\/revisions"}],"predecessor-version":[{"id":2919,"href":"https:\/\/www.conventuspolymers.com\/es\/wp-json\/wp\/v2\/pages\/2341\/revisions\/2919"}],"up":[{"embeddable":true,"href":"https:\/\/www.conventuspolymers.com\/es\/wp-json\/wp\/v2\/pages\/2578"}],"wp:attachment":[{"href":"https:\/\/www.conventuspolymers.com\/es\/wp-json\/wp\/v2\/media?parent=2341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}